{"id":300,"date":"2021-04-28T14:04:02","date_gmt":"2021-04-28T17:04:02","guid":{"rendered":"http:\/\/1321dd813b.nxcli.io.php72-4.phx1-1.websitetestlink.com\/?page_id=300"},"modified":"2026-04-27T12:57:48","modified_gmt":"2026-04-27T15:57:48","slug":"la-empresa","status":"publish","type":"page","link":"https:\/\/flamencotour.com\/pt\/la-empresa\/","title":{"rendered":"A EMPRESA"},"content":{"rendered":"<div class=\"container section-title-container\" ><h1 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >A EMPRESA<\/span><b aria-hidden=\"true\"><\/b><\/h1><\/div>\n<div class=\"row\"  id=\"row-1924938975\">\n\n\t<div id=\"col-697118569\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-536969124\" class=\"text\">\n\t\t\n<h2>Passeio Flamenco<\/h2>\n<p><strong>Passeio Flamenco<\/strong> \u00c9 uma empresa de turismo receptivo sediada em Puerto Madryn, Argentina. Foi fundada em 1967 e desde 2002 opera sob o nome corporativo <strong>DIAGUES SRL<\/strong>. Com mais de cinco d\u00e9cadas de experi\u00eancia, nos consolidamos como l\u00edderes no setor, oferecendo experi\u00eancias tur\u00edsticas de alta qualidade que destacam a riqueza natural e cultural da regi\u00e3o da Patag\u00f4nia.<\/p>\n<p>Nossa equipe, formada por profissionais jovens e din\u00e2micos, se dedica a projetar e oferecer uma ampla gama de excurs\u00f5es e atividades que destacam a biodiversidade e as paisagens \u00fanicas da Patag\u00f4nia.<\/p>\n<p><strong>Nossas propostas incluem:<\/strong><\/p>\n<p><strong>Pen\u00ednsula Vald\u00e9s Dia Inteiro:<br \/><\/strong>Uma excurs\u00e3o completa para descobrir a biodiversidade e as paisagens \u00fanicas da Pen\u00ednsula Vald\u00e9s.<\/p>\n<p><strong>Passeio pela cidade de Puerto Madryn:<\/strong><br \/>Um passeio pelos patrim\u00f4nios hist\u00f3ricos, arquitet\u00f4nicos, culturais e naturais da cidade.<\/p>\n<p><strong>Dia de campo na Est\u00e2ncia \u00abEl Pedral\u00bb:<\/strong><br \/>Uma experi\u00eancia aut\u00eantica na Patag\u00f4nia, incluindo visitas ao Farol de Punta Ninfas e caminhadas guiadas entre pinguins de Magalh\u00e3es.<\/p>\n<p style=\"font-weight: 400;\">Em <strong>Passeio Flamenco<\/strong>Estamos comprometidos com a inova\u00e7\u00e3o e a sustentabilidade, adaptando-nos constantemente \u00e0s tend\u00eancias do mercado tur\u00edstico e promovendo pr\u00e1ticas ambientalmente respons\u00e1veis. Nosso objetivo \u00e9 proporcionar a cada viajante uma experi\u00eancia \u00fanica e memor\u00e1vel, destacando a beleza e a singularidade da regi\u00e3o da Patag\u00f4nia.<\/p>\n\t\t\n<style>\n#text-536969124 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2035694711\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_324298426\">\n\t\t\t\t\t\t<div data-animate=\"fadeInRight\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"947\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2026\/04\/lamperesa-edt.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2026\/04\/lamperesa-edt.png 717w, https:\/\/flamencotour.com\/wp-content\/uploads\/2026\/04\/lamperesa-edt-303x400.png 303w, https:\/\/flamencotour.com\/wp-content\/uploads\/2026\/04\/lamperesa-edt-606x800.png 606w, https:\/\/flamencotour.com\/wp-content\/uploads\/2026\/04\/lamperesa-edt-9x12.png 9w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_324298426 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1915600236\">\n\n\t<div id=\"col-1024497520\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >como trabalhamos<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n<div class=\"accordion\">\n\t<div id=\"accordion-3511347997\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3511347997-label\" class=\"accordion-title plain\" aria-expanded=\"false\" aria-controls=\"accordion-3511347997-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Na Flamenco Tour, garantimos que nosso servi\u00e7o come\u00e7a muito antes dos passageiros chegarem \u00e0 nossa \u00e1rea, implementando processos bem definidos:<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3511347997-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3511347997-label\">\n\t\t\t\n<p>\u2714 N\u00f3s projetamos cada passeio para capturar a ess\u00eancia e a magia de cada lugar que visitamos, oferecendo experi\u00eancias aut\u00eanticas e memor\u00e1veis para nossos clientes.<\/p>\n<p>\u2714 Selecionamos cuidadosamente cada provedor e correspondente para garantir qualidade consistente em todos os servi\u00e7os que oferecemos, ao mesmo tempo em que mantemos pre\u00e7os competitivos para nossos clientes.<\/p>\n<p>\u2714 Organizamos programas convencionais e alternativos que abrangem uma ampla gama de op\u00e7\u00f5es, desde turismo de aventura at\u00e9 turismo rural, gastron\u00f4mico e cultural.<\/p>\n<p>Nosso objetivo \u00e9 proporcionar aos nossos clientes a oportunidade de explorar nossa \u00e1rea de uma forma \u00fanica e diversa, adaptando-nos aos seus interesses e prefer\u00eancias.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-10443886\" class=\"accordion-item\">\n\t\t<a id=\"accordion-10443886-label\" class=\"accordion-title plain\" aria-expanded=\"false\" aria-controls=\"accordion-10443886-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Quando voc\u00ea faz sua primeira consulta:<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-10443886-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-10443886-label\">\n\t\t\t\n<p>N\u00f3s nos esfor\u00e7amos para oferecer um atendimento excepcional ao cliente desde o primeiro contato at\u00e9 a conclus\u00e3o da sua viagem.<\/p>\n<p>Aqui detalho como trabalhamos desde a primeira consulta ou com sua solicita\u00e7\u00e3o de reserva:<\/p>\n<p>\u2714 Oferecemos uma ampla gama de meios tecnol\u00f3gicos para comunica\u00e7\u00e3o, incluindo e-mail, Instagram, Facebook, LinkedIn, TripAdvisor, bem como telefones celulares.<\/p>\n<p>Al\u00e9m disso, fornecemos n\u00fameros de emerg\u00eancia dispon\u00edveis 24 horas por dia, 365 dias por ano, para garantir a tranquilidade e a seguran\u00e7a de nossos clientes em todos os momentos.<\/p>\n<p>\u2714 Cada consulta ou solicita\u00e7\u00e3o de reserva \u00e9 tratada de forma personalizada pela nossa equipe. Embora tenhamos alguns programas modelo, sempre nos adaptamos \u00e0s necessidades espec\u00edficas de cada cliente. Trabalhamos em estreita colabora\u00e7\u00e3o com eles para entender seus gostos, prefer\u00eancias e or\u00e7amento, para que possamos elaborar e cotar um itiner\u00e1rio personalizado.<\/p>\n<p>Nosso objetivo \u00e9 aproveitar ao m\u00e1ximo nosso conhecimento e experi\u00eancia da regi\u00e3o para oferecer uma experi\u00eancia \u00fanica e satisfat\u00f3ria.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-4015178708\" class=\"accordion-item\">\n\t\t<a id=\"accordion-4015178708-label\" class=\"accordion-title plain\" aria-expanded=\"false\" aria-controls=\"accordion-4015178708-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Quando o passageiro chega:<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-4015178708-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-4015178708-label\">\n\t\t\t\n<p>Garantimos um servi\u00e7o completo e personalizado desde a chegada dos nossos passageiros:<\/p>\n<p>\u2714 Acompanhamos nossos passageiros desde o momento em que chegam, oferecendo suporte por meio de itiner\u00e1rios virtuais, vouchers e folhetos digitais. Nossa equipe est\u00e1 dispon\u00edvel para fornecer aconselhamento e assist\u00eancia no que for necess\u00e1rio.<\/p>\n<p>\u2714 Oferecemos monitoramento personalizado durante todo o itiner\u00e1rio, verificando e controlando hor\u00e1rios de voos, programando excurs\u00f5es com base nas condi\u00e7\u00f5es clim\u00e1ticas e coordenando com os hot\u00e9is em cada caso para garantir uma experi\u00eancia tranquila.<\/p>\n<p>\u2714 Seu vendedor ou consultor ser\u00e1 quem estar\u00e1 esperando por voc\u00ea na sua chegada em nossa cidade. Conhecendo voc\u00ea e suas necessidades, eles estar\u00e3o preparados para lhe fornecer assist\u00eancia e suporte em todos os momentos da sua estadia. Mas n\u00e3o se preocupe, caso essa pessoa n\u00e3o esteja dispon\u00edvel, outra pessoa saber\u00e1 da sua reserva para poder ajud\u00e1-lo no que voc\u00ea precisar.<\/p>\n<p>Na Flamenco Tour, nos esfor\u00e7amos para tornar cada etapa da sua viagem confort\u00e1vel, segura e memor\u00e1vel.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-4213292607\" class=\"accordion-item\">\n\t\t<a id=\"accordion-4213292607-label\" class=\"accordion-title plain\" aria-expanded=\"false\" aria-controls=\"accordion-4213292607-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Nossa paix\u00e3o:<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-4213292607-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-4213292607-label\">\n\t\t\t\n<p>Nossa paix\u00e3o pelo que fazemos se reflete em todos os aspectos do nosso trabalho:<\/p>\n<p>\u2714 Valorizamos a beleza \u00fanica e o car\u00e1ter excepcional da regi\u00e3o em que vivemos e trabalhamos.<\/p>\n<p>Estamos comprometidos em proporcionar aos nossos passageiros experi\u00eancias memor\u00e1veis, garantindo que cada lembran\u00e7a reflita a qualidade dos nossos servi\u00e7os e o carinho do nosso atendimento. Tudo isso com profundo respeito ao meio ambiente, minimizando nosso impacto na natureza, protegendo o meio ambiente e apoiando ativamente aqueles que compartilham esse compromisso.<\/p>\n<p>\u2714 Queremos que cada um dos nossos passageiros retorne \u00e0 sua cidade de origem com a certeza de ter vivido uma experi\u00eancia \u00fanica e memor\u00e1vel. Estamos orgulhosos de que voc\u00ea volte para casa determinado a recomendar nosso destino e agradecer ao seu Agente de Viagens por ter lhe proporcionado uma experi\u00eancia t\u00e3o gratificante.<\/p>\n<p>Em <strong>Passeio Flamenco<\/strong>Nossa paix\u00e3o \u00e9 tornar cada viagem inesquec\u00edvel, inspiradora e cheia de momentos especiais que ficar\u00e3o na mem\u00f3ria dos nossos passageiros.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-201923683\" class=\"accordion-item\">\n\t\t<a id=\"accordion-201923683-label\" class=\"accordion-title plain\" href=\"#accordion-item-el-feedback...\" aria-expanded=\"false\" aria-controls=\"accordion-201923683-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>O Feedback...<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-201923683-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-201923683-label\">\n\t\t\t\n<p>Valorizamos muito o feedback de nossos passageiros e agentes de viagens e nos esfor\u00e7amos para garantir que sua experi\u00eancia seja a mais satisfat\u00f3ria poss\u00edvel:<\/p>\n<p>\u2714 Para garantir que atendemos \u00e0s expectativas dos nossos clientes, temos um sistema de medi\u00e7\u00e3o de satisfa\u00e7\u00e3o. Este sistema nos permite coletar feedback e opini\u00f5es, fornecendo informa\u00e7\u00f5es valiosas para melhorar continuamente nossos servi\u00e7os, criar novos passeios e aprimorar a experi\u00eancia com nossa equipe.<\/p>\n<p>\u2714 Analisamos de perto os resultados dessas medi\u00e7\u00f5es para identificar \u00e1reas de oportunidade e tomar medidas corretivas quando necess\u00e1rio. Nosso objetivo \u00e9 melhorar a cada dia e garantir que cada experi\u00eancia com o Flamenco Tour seja excepcional.<\/p>\n<p>Recebemos feedback dos nossos clientes, ele \u00e9 essencial para o nosso processo de melhoria cont\u00ednua. Estamos comprometidos em usar esse feedback para continuar a fornecer servi\u00e7os de alta qualidade e superar as expectativas de nossos clientes em todos os momentos.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-245998175\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-245998175 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse row-full-width align-center parallax\"  id=\"row-1038394641\">\n\n\t<div id=\"col-681780782\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-921416202\" class=\"text\">\n\t\t\n<div class=\"bg-parallax\">\n<h2 class=\"lead\" style=\"text-align: center;\">QUEM SOMOS<\/h2>\n<p><strong>Passeio Flamenco<\/strong> \u00e9 uma empresa de turismo receptivo com trajet\u00f3ria consolidada em Puerto Madryn. Somos especialistas em oferecer experi\u00eancias de alta qualidade que valorizam a riqueza natural e cultural da regi\u00e3o, sempre com foco na sustentabilidade, seguran\u00e7a e excel\u00eancia no atendimento. Nosso compromisso com a inova\u00e7\u00e3o e a melhoria cont\u00ednua nos permite superar as expectativas dos nossos clientes e nos consolidar como refer\u00eancia no setor de turismo.<\/p>\n<p><strong>Nossa Pol\u00edtica de Qualidade e Compromisso:<\/strong> Em <strong>Passeio Flamenco<\/strong>Trabalhamos sob um sistema de gest\u00e3o de qualidade que garante o cumprimento de regulamenta\u00e7\u00f5es reconhecidas, incluindo IRAM SECTUR, Compromisso de Qualidade e Todos Bem-vindos, entre outras. Nossa miss\u00e3o \u00e9 oferecer experi\u00eancias seguras, respons\u00e1veis e memor\u00e1veis, alinhadas aos mais altos padr\u00f5es do setor.<\/p>\n<p>Para atingir esse objetivo, nos concentramos em:<\/p>\n<p><strong>Excel\u00eancia e Regulamenta\u00e7\u00e3o:<br \/><\/strong>Implementamos um sistema de gest\u00e3o da qualidade que garante o cumprimento das normas vigentes e das boas pr\u00e1ticas do setor do turismo.<\/p>\n<p><strong>Desenvolvimento de Talentos:<\/strong> <br \/>Nossa equipe \u00e9 o pilar do nosso sucesso. Incentivamos a forma\u00e7\u00e3o cont\u00ednua, promovendo um ambiente de trabalho seguro e motivador, onde a dedica\u00e7\u00e3o e a paix\u00e3o s\u00e3o a marca de cada experi\u00eancia.<\/p>\n<p><strong>Seguran\u00e7a e conforto:<\/strong> <br \/>Garantimos unidades de transporte modernas, confort\u00e1veis e seguras, com rigorosos controles preventivos e cumprimento de todas as normas vigentes.<\/p>\n<p><strong>Preven\u00e7\u00e3o e Melhoria Cont\u00ednua:<\/strong> <br \/>Adotamos uma abordagem proativa para identificar e prevenir n\u00e3o conformidades, otimizando todos os aspectos da nossa opera\u00e7\u00e3o.<\/p>\n<p><strong>Rela\u00e7\u00f5es estrat\u00e9gicas:<\/strong> <br \/>Fortalecemos alian\u00e7as com os principais players do setor para melhorar a qualidade e o desenvolvimento sustent\u00e1vel de nossas atividades.<\/p>\n<p><strong>Comunica\u00e7\u00e3o transparente:<br \/><\/strong>Mantemos um di\u00e1logo constante com nossos visitantes, fornecendo informa\u00e7\u00f5es claras e promovendo a preven\u00e7\u00e3o de riscos.<\/p>\n<p><strong>Compromisso com a satisfa\u00e7\u00e3o:<br \/><\/strong>N\u00e3o apenas cumprimos nossas promessas, mas trabalhamos para superar as expectativas daqueles que nos escolhem.<\/p>\n<p><strong>Sustentabilidade e Responsabilidade Ambiental:<br \/><\/strong> Promovemos pr\u00e1ticas respons\u00e1veis, conscientizando nossos visitantes sobre a import\u00e2ncia de proteger o ambiente natural, cultural e humano de cada destino.<\/p>\n<p>Em <strong>Passeio Flamenco<\/strong>Nossa vis\u00e3o \u00e9 clara: ser l\u00edderes em turismo respons\u00e1vel e sustent\u00e1vel, oferecendo experi\u00eancias aut\u00eanticas, seguras e enriquecedoras para todos os viajantes.<\/p>\n<h3>Miss\u00e3o<\/h3>\n<p>Em <strong>Passeio Flamenco<\/strong>Nossa miss\u00e3o \u00e9 proporcionar excelentes experi\u00eancias tur\u00edsticas em Puerto Madryn e na regi\u00e3o da Patag\u00f4nia, destacando sua riqueza natural e cultural por meio de um servi\u00e7o profissional, seguro e sustent\u00e1vel. Estamos comprometidos com a qualidade, a inova\u00e7\u00e3o e o desenvolvimento do turismo respons\u00e1vel, garantindo a satisfa\u00e7\u00e3o do cliente, minimizando o impacto ambiental e promovendo o respeito \u00e0 natureza e \u00e0s comunidades locais.<\/p>\n<h3>Vis\u00e3o<\/h3>\n<p>Ser a empresa l\u00edder em turismo receptivo na regi\u00e3o, reconhecida pela excel\u00eancia no atendimento, pelo comprometimento com a sustentabilidade e pela capacidade de inova\u00e7\u00e3o. Nosso objetivo \u00e9 fazer a diferen\u00e7a no setor estabelecendo padr\u00f5es de qualidade que contribuam para o desenvolvimento do turismo respons\u00e1vel, gerando impacto positivo no meio ambiente e criando experi\u00eancias inesquec\u00edveis para quem nos escolhe.<\/p>\n<\/div>\n\t\t\n<style>\n#text-921416202 {\n  color: rgb(0,0,0);\n}\n#text-921416202 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-681780782 > .col-inner {\n  padding: 50px 25px 25px 25px;\n  margin: 10px 10px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Nossa equipe<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row\"  id=\"row-1645039926\">\n\n\t<div id=\"col-1178620098\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Matias-Garcia-socio-Gerente-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">MATIAS GARC\u00cdA<\/h4>\n<p style=\"text-align: center;\">S\u00f3cio-gerente<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1660948886\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Javier-Marcos-Operaciones-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">JAVIER MARCOS<\/h4>\n<p style=\"text-align: center;\">Opera\u00e7\u00f5es<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-776138119\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/05\/Maria-Celeste-Garcia-ventas-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">MARIA CELESTE GARC\u00cdA<\/h4>\n<p style=\"text-align: center;\">Vendas<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2048299437\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/GISELA-ventas-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">GISELA<\/h4>\n<p style=\"text-align: center;\">Vendas<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1645039926 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-764284581\">\n\n\t<div id=\"col-144367340\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"481\" height=\"481\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/10\/sole-ventas.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/10\/sole-ventas.jpg 481w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/10\/sole-ventas-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/10\/sole-ventas-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/10\/sole-ventas-100x100.jpg 100w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">\u00daNICO<\/h4>\n<p style=\"text-align: center;\">Vendas<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-41593631\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-12x12.jpg 12w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2023\/06\/51c8e7fd-4852-437b-9317-2947cde8bf88-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">ROMINA<\/h4>\n<p style=\"text-align: center;\">Vendas<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1032431347\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-fade-in\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea.jpg 1080w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-400x400.jpg 400w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-800x800.jpg 800w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-280x280.jpg 280w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-768x768.jpg 768w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-1000x1000.jpg 1000w, https:\/\/flamencotour.com\/wp-content\/uploads\/2021\/06\/Nora-idonea-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4 style=\"text-align: center;\">NORA<\/h4>\n<p style=\"text-align: center;\">Ideal<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-764284581 > .col > .col-inner {\n  padding: 20px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-402449061\">\n\n\t<div id=\"col-93281474\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:75%;\"><\/div><\/div>\n<p style=\"text-align: center;\"><span style=\"font-size: 110%;\"><strong>Reclama\u00e7\u00e3o\/Reivindica\u00e7\u00e3o:<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Se voc\u00ea acredita que n\u00e3o cumprimos os regulamentos aplic\u00e1veis do minist\u00e9rio nacional do turismo ou o que est\u00e1 acordado no contrato,<br \/>Voc\u00ea pode fazer uma reclama\u00e7\u00e3o clicando aqui:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.argentina.gob.ar\/servicio\/presentar-una-denuncia-contra-una-agencia-de-viajes\">https:\/\/www.argentina.gob.ar\/servicio\/presentar-una-denuncia-contra-una-agencia-de-viajes<\/a><\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:75%;\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-300","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA EMPRESA - Flamenco Tour<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamencotour.com\/pt\/la-empresa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA EMPRESA - Flamenco Tour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamencotour.com\/pt\/la-empresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Flamenco Tour\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T15:57:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/flamencotour.com\\\/la-empresa\\\/\",\"url\":\"https:\\\/\\\/flamencotour.com\\\/la-empresa\\\/\",\"name\":\"LA EMPRESA - Flamenco Tour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flamencotour.com\\\/en\\\/#website\"},\"datePublished\":\"2021-04-28T17:04:02+00:00\",\"dateModified\":\"2026-04-27T15:57:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flamencotour.com\\\/la-empresa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/flamencotour.com\\\/la-empresa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flamencotour.com\\\/la-empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/flamencotour.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA EMPRESA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flamencotour.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/flamencotour.com\\\/en\\\/\",\"name\":\"Flamenco Tour\",\"description\":\"Excursiones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flamencotour.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA EMPRESA - Flamenco Tour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamencotour.com\/pt\/la-empresa\/","og_locale":"pt_BR","og_type":"article","og_title":"LA EMPRESA - Flamenco Tour","og_url":"https:\/\/flamencotour.com\/pt\/la-empresa\/","og_site_name":"Flamenco Tour","article_modified_time":"2026-04-27T15:57:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flamencotour.com\/la-empresa\/","url":"https:\/\/flamencotour.com\/la-empresa\/","name":"LA EMPRESA - Flamenco Tour","isPartOf":{"@id":"https:\/\/flamencotour.com\/en\/#website"},"datePublished":"2021-04-28T17:04:02+00:00","dateModified":"2026-04-27T15:57:48+00:00","breadcrumb":{"@id":"https:\/\/flamencotour.com\/la-empresa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flamencotour.com\/la-empresa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flamencotour.com\/la-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/flamencotour.com\/"},{"@type":"ListItem","position":2,"name":"LA EMPRESA"}]},{"@type":"WebSite","@id":"https:\/\/flamencotour.com\/en\/#website","url":"https:\/\/flamencotour.com\/en\/","name":"Passeio Flamenco","description":"Excurs\u00f5es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamencotour.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/pages\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":6,"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/pages\/300\/revisions"}],"predecessor-version":[{"id":13159,"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/pages\/300\/revisions\/13159"}],"wp:attachment":[{"href":"https:\/\/flamencotour.com\/pt\/wp-json\/wp\/v2\/media?parent=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}